{"id":3117,"date":"2025-09-10T10:30:37","date_gmt":"2025-09-10T10:30:37","guid":{"rendered":"https:\/\/onivia.net\/es\/?p=3117"},"modified":"2026-06-24T08:38:11","modified_gmt":"2026-06-24T08:38:11","slug":"onivia-lanza-fibra-x-la-nueva-generacion-de-conectividad-ultrarrapida","status":"publish","type":"post","link":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/","title":{"rendered":"Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida"},"content":{"rendered":"<p>Onivia, operador mayorista de fibra neutro e independiente, anuncia el lanzamiento de <strong>Fibra X<\/strong>, su nuevo servicio mayorista de conectividad basado en <strong>tecnolog\u00eda XGS-PON,<\/strong> que lleva la conectividad ultrarr\u00e1pida al siguiente nivel. Con velocidades sim\u00e9tricas de hasta <strong>3Gbps, 5Gbps y 10Gbps<\/strong>, Onivia se convierte en <strong>el primer operador mayorista del pa\u00eds en ofrecer esta tecnolog\u00eda a operadores de telecomunicaciones y empresas.<\/strong><\/p>\n<p>Este nuevo <strong>hito en la evoluci\u00f3n del mercado de fibra mayorista en Espa\u00f1a<\/strong> permitir\u00e1, por primera vez, que los operadores puedan ofrecer <strong>velocidades premium<\/strong> <strong>tanto en \u00e1reas urbanas como rurales<\/strong> donde ya est\u00e1 presente la red de Onivia. Con Fibra X, los proveedores de servicios de telecomunicaciones podr\u00e1n <strong>diferenciar su oferta, fidelizar clientes y captar nuevos nichos de mercado<\/strong> sin necesidad de desplegar infraestructura propia.<\/p>\n<p>Basado en tecnolog\u00eda XGS-PON, Fibra X proporciona velocidades sim\u00e9tricas de hasta 10Gbps, mayor estabilidad de red y latencias ultrabajas, incluso en escenarios de alta demanda. Estas caracter\u00edsticas hacen posible una experiencia fluida en streaming 4K y 8K, cloud gaming, realidad virtual y teletrabajo intensivo. Dise\u00f1ada para hogares y entornos hiperconectados, Fibra X garantiza el rendimiento con m\u00faltiples dispositivos conectados de forma simult\u00e1nea y con alta demanda de ancho de banda, lo que lo convierte en una prestaci\u00f3n \u00f3ptima tanto para usuarios residenciales avanzados como para pymes y negocios con necesidades cr\u00edticas de conectividad.<\/p>\n<p>Con todo, la puesta en marcha de este servicio por parte de Onivia supone <strong>democratizar el acceso a tecnolog\u00edas de \u00faltima generaci\u00f3n eliminando barreras de entrada<\/strong>, comparable a la de los enlaces dedicados utilizados por grandes corporaciones, pero accesible para operadores y empresas de cualquier tama\u00f1o y sin necesidad de que realicen inversiones en infraestructura propia. Asimismo, refrenda la posici\u00f3n de ONIVIA como la red alternativa de referencia en el mercado espa\u00f1ol, combinando innovaci\u00f3n tecnol\u00f3gica con un modelo mayorista neutro y una gran capilaridad regional.<\/p>\n<p>\u201cEl servicio <em>Fibra X refuerza nuestro compromiso de <strong>democratizar el acceso a tecnolog\u00edas de \u00faltima generaci\u00f3n eliminando barreras de entrada.<\/strong> Somos pioneros en ofrecer XGS-PON a nivel mayorista en Espa\u00f1a, y ponemos esta tecnolog\u00eda al alcance de todo tipo de entornos, incluidos los rurales, para que nuestros operadores clientes puedan crecer, diferenciarse y ofrecer a los usuarios finales la mejor experiencia<\/em>\u201d, afirma <strong>Pedro Fern\u00e1ndez, Chief Commercial Officer de Onivia<\/strong>. \u201c<em>ONIVIA pone al servicio de los operadores y empresas una red de \u00faltima generaci\u00f3n, preparada para acompa\u00f1ar la evoluci\u00f3n de sus servicios y responder a las nuevas demandas digitales con fiabilidad, escalabilidad y neutralidad<\/em>\u201d, a\u00f1ade.<\/p>\n<p><strong>Servicio preparado para 5 millones de hogares y negocios (FTTH) en 12 provincias<\/strong><\/p>\n<p>Actualmente, el nuevo servicio mayorista de conectividad ultrarr\u00e1pida de Onivia, Fibra X, ya es posible para cerca de 5<strong> millones de hogares y negocios<\/strong> en 186 municipios de 12 provincias espa\u00f1olas (\u00c1vila, Segovia, Albacete, Ciudad Real, Cuenca, Guadalajara, Toledo, Madrid, Alicante\/Alacant, Castell\u00f3n\/Castell\u00f3, Valencia\/Val\u00e8ncia y Murcia). La compa\u00f1\u00eda ir\u00e1 extendi\u00e9ndolo al resto de territorios de su red de forma gradual.<\/p>\n<p>Fibra X est\u00e1 plenamente disponible para<strong> operadores y empresas<\/strong> dentro del portfolio comercial de Onivia. Su integraci\u00f3n sencilla en las plataformas existentes y el soporte especializado de Onivia facilitar\u00e1 su adopci\u00f3n en todo el ecosistema mayorista.<\/p>\n<hr \/>\n<p><span data-contrast=\"auto\">Publicado el 09 de septiembre de 2025.<\/span><\/p>","protected":false},"excerpt":{"rendered":"Onivia, operador mayorista de fibra neutro e independiente, anuncia el lanzamiento de Fibra X, su nuevo servicio mayorista de conectividad basado en tecnolog\u00eda XGS-PON, que lleva la conectividad ultrarr\u00e1pida al siguiente nivel. Con velocidades sim\u00e9tricas de hasta 3Gbps, 5Gbps y 10Gbps, Onivia se convierte en el primer operador mayorista del pa\u00eds en ofrecer esta tecnolog\u00eda&#8230;","protected":false},"author":6,"featured_media":3116,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-3117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prensa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida - Onivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida[:en]Onivia launches Fibra X, the next generation of ultrafast connectivity[:] - Onivia\" \/>\n<meta property=\"og:description\" content=\"Onivia, operador mayorista de fibra neutro e independiente, anuncia el lanzamiento de Fibra X, su nuevo servicio mayorista de conectividad basado en tecnolog\u00eda XGS-PON, que lleva la conectividad ultrarr\u00e1pida al siguiente nivel. Con velocidades sim\u00e9tricas de hasta 3Gbps, 5Gbps y 10Gbps, Onivia se convierte en el primer operador mayorista del pa\u00eds en ofrecer esta tecnolog\u00eda...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/\" \/>\n<meta property=\"og:site_name\" content=\"Onivia\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-10T10:30:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T08:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/onivia.net\/wp-content\/uploads\/2025\/09\/fibra-x-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"iciar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"iciar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/\"},\"author\":{\"name\":\"iciar\",\"@id\":\"https:\\\/\\\/onivia.net\\\/en\\\/#\\\/schema\\\/person\\\/b05a618090eafe74e6d0a228b25697df\"},\"headline\":\"Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida\",\"datePublished\":\"2025-09-10T10:30:37+00:00\",\"dateModified\":\"2026-06-24T08:38:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/\"},\"wordCount\":1053,\"image\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onivia.net\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fibra-x-1.png\",\"articleSection\":[\"Onivia en la prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/\",\"url\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/\",\"name\":\"[:es]Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida[:en]Onivia launches Fibra X, the next generation of ultrafast connectivity[:] - Onivia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/onivia.net\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fibra-x-1.png\",\"datePublished\":\"2025-09-10T10:30:37+00:00\",\"dateModified\":\"2026-06-24T08:38:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/en\\\/#\\\/schema\\\/person\\\/b05a618090eafe74e6d0a228b25697df\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/onivia.net\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fibra-x-1.png\",\"contentUrl\":\"https:\\\/\\\/onivia.net\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/fibra-x-1.png\",\"width\":850,\"height\":528},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/onivia.net\\\/es\\\/fibra-x-onivia-ultrarrapida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/onivia.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/onivia.net\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/onivia.net\\\/en\\\/\",\"name\":\"Onivia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/onivia.net\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/onivia.net\\\/en\\\/#\\\/schema\\\/person\\\/b05a618090eafe74e6d0a228b25697df\",\"name\":\"iciar\",\"url\":\"https:\\\/\\\/onivia.net\\\/es\\\/author\\\/iciar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida[:en]Onivia launches Fibra X, the next generation of ultrafast connectivity[:] - Onivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/","og_locale":"es_ES","og_type":"article","og_title":"[:es]Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida[:en]Onivia launches Fibra X, the next generation of ultrafast connectivity[:] - Onivia","og_description":"Onivia, operador mayorista de fibra neutro e independiente, anuncia el lanzamiento de Fibra X, su nuevo servicio mayorista de conectividad basado en tecnolog\u00eda XGS-PON, que lleva la conectividad ultrarr\u00e1pida al siguiente nivel. Con velocidades sim\u00e9tricas de hasta 3Gbps, 5Gbps y 10Gbps, Onivia se convierte en el primer operador mayorista del pa\u00eds en ofrecer esta tecnolog\u00eda...","og_url":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/","og_site_name":"Onivia","article_published_time":"2025-09-10T10:30:37+00:00","article_modified_time":"2026-06-24T08:38:11+00:00","og_image":[{"width":850,"height":528,"url":"https:\/\/onivia.net\/wp-content\/uploads\/2025\/09\/fibra-x-1.png","type":"image\/png"}],"author":"iciar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"iciar","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/#article","isPartOf":{"@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/"},"author":{"name":"iciar","@id":"https:\/\/onivia.net\/en\/#\/schema\/person\/b05a618090eafe74e6d0a228b25697df"},"headline":"Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida","datePublished":"2025-09-10T10:30:37+00:00","dateModified":"2026-06-24T08:38:11+00:00","mainEntityOfPage":{"@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/"},"wordCount":1053,"image":{"@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/#primaryimage"},"thumbnailUrl":"https:\/\/onivia.net\/wp-content\/uploads\/2025\/09\/fibra-x-1.png","articleSection":["Onivia en la prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/","url":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/","name":"[:es]Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida[:en]Onivia launches Fibra X, the next generation of ultrafast connectivity[:] - Onivia","isPartOf":{"@id":"https:\/\/onivia.net\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/#primaryimage"},"image":{"@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/#primaryimage"},"thumbnailUrl":"https:\/\/onivia.net\/wp-content\/uploads\/2025\/09\/fibra-x-1.png","datePublished":"2025-09-10T10:30:37+00:00","dateModified":"2026-06-24T08:38:11+00:00","author":{"@id":"https:\/\/onivia.net\/en\/#\/schema\/person\/b05a618090eafe74e6d0a228b25697df"},"breadcrumb":{"@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/#primaryimage","url":"https:\/\/onivia.net\/wp-content\/uploads\/2025\/09\/fibra-x-1.png","contentUrl":"https:\/\/onivia.net\/wp-content\/uploads\/2025\/09\/fibra-x-1.png","width":850,"height":528},{"@type":"BreadcrumbList","@id":"https:\/\/onivia.net\/es\/fibra-x-onivia-ultrarrapida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/onivia.net\/es\/"},{"@type":"ListItem","position":2,"name":"Onivia lanza Fibra X, la nueva generaci\u00f3n de conectividad ultrarr\u00e1pida"}]},{"@type":"WebSite","@id":"https:\/\/onivia.net\/en\/#website","url":"https:\/\/onivia.net\/en\/","name":"Onivia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/onivia.net\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/onivia.net\/en\/#\/schema\/person\/b05a618090eafe74e6d0a228b25697df","name":"iciar","url":"https:\/\/onivia.net\/es\/author\/iciar\/"}]}},"_links":{"self":[{"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/posts\/3117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/comments?post=3117"}],"version-history":[{"count":3,"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/posts\/3117\/revisions"}],"predecessor-version":[{"id":3609,"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/posts\/3117\/revisions\/3609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/media\/3116"}],"wp:attachment":[{"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/media?parent=3117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/categories?post=3117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/onivia.net\/es\/wp-json\/wp\/v2\/tags?post=3117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}